{"id":7478,"date":"2022-12-20T09:30:05","date_gmt":"2022-12-20T09:30:05","guid":{"rendered":"https:\/\/www.parcozoopuntaverde.it\/lo-zoo-sostenibile\/"},"modified":"2025-08-22T09:26:28","modified_gmt":"2025-08-22T09:26:28","slug":"lo-zoo-sostenibile","status":"publish","type":"page","link":"https:\/\/www.parcozoopuntaverde.it\/en\/lo-zoo-sostenibile\/","title":{"rendered":"Lo Zoo sostenibile"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7478\" class=\"elementor elementor-7478 elementor-1149\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dda2d7b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"dda2d7b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2d4dec\" data-id=\"e2d4dec\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f9c646 e-transform elementor-widget elementor-widget-heading\" data-id=\"0f9c646\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-6,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">LO ZOO<br \/>SOSTENIBILE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec527b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec527b5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ef93ca\" data-id=\"8ef93ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe525ea elementor-widget elementor-widget-text-editor\" data-id=\"fe525ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Crediamo in un futuro migliore in cui l\u2019uomo possa vivere in armonia con la Natura. Poniamo attenzione al peso che le nostre azioni possono avere sull\u2019ambiente e cerchiamo continuamente di migliorarci per diventare sempre pi\u00f9 sostenibili.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb45e0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb45e0b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2aa7b0f\" data-id=\"2aa7b0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-89b54d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89b54d2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6458378\" data-id=\"6458378\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-504b28f elementor-widget elementor-widget-image\" data-id=\"504b28f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"337\" height=\"398\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bidone-differenziato.png\" class=\"attachment-large size-large wp-image-7494\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bidone-differenziato.png 337w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bidone-differenziato-254x300.png 254w\" sizes=\"(max-width: 337px) 100vw, 337px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-678f6e5\" data-id=\"678f6e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af821f9 elementor-widget elementor-widget-heading\" data-id=\"af821f9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RACCOLTA DIFFERENZIATA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf85dec elementor-widget elementor-widget-text-editor\" data-id=\"bf85dec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Riciclare e ridurre i rifiuti \u00e8 un gesto semplice che ha impatti molto positivi sull\u2019ambiente. All\u2019interno dello zoo troverete i bidoni per la raccolta differenziata dell\u2019organico, della plastica-vetro e lattine e delle componenti non riciclabili.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ff21373 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff21373\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a02538\" data-id=\"3a02538\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d11cd42 elementor-widget elementor-widget-image\" data-id=\"d11cd42\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"450\" height=\"356\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/macchina-elettrica.png\" class=\"attachment-large size-large wp-image-7503\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/macchina-elettrica.png 450w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/macchina-elettrica-300x237.png 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f3b6c83\" data-id=\"f3b6c83\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1160206 elementor-widget elementor-widget-heading\" data-id=\"1160206\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MEZZI ELETTRICI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df68447 elementor-widget elementor-widget-text-editor\" data-id=\"df68447\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La riduzione delle emissioni di gas serra, come l\u2019anidride carbonica, contrasta il surriscaldamento globale. Tutti i mezzi di spostamento utilizzati dai guardiani degli animali, dai giardinieri, dai manutentori e dalla direzione sono elettrici.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7764e0f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7764e0f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-35b7b52\" data-id=\"35b7b52\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df0b0b3 elementor-widget elementor-widget-image\" data-id=\"df0b0b3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"439\" height=\"546\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bicchiere-e-cannuccia.png\" class=\"attachment-large size-large wp-image-7492\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bicchiere-e-cannuccia.png 439w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bicchiere-e-cannuccia-241x300.png 241w\" sizes=\"(max-width: 439px) 100vw, 439px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3985c0d\" data-id=\"3985c0d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b077864 elementor-widget elementor-widget-heading\" data-id=\"b077864\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CANNUCCE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48f2eb8 elementor-widget elementor-widget-text-editor\" data-id=\"48f2eb8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLe cannucce sono tra i dieci rifiuti pi\u00f9 comuni nei nostri mari e sulle nostre spiagge. Al bar verranno consegnate le cannucce compostabili solo su richiesta, se strettamente necessarie.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fc47932 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc47932\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ecfbba6\" data-id=\"ecfbba6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44a3d6a elementor-widget elementor-widget-image\" data-id=\"44a3d6a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"494\" height=\"633\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/borsa-spesa.png\" class=\"attachment-large size-large wp-image-7495\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/borsa-spesa.png 494w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/borsa-spesa-234x300.png 234w\" sizes=\"(max-width: 494px) 100vw, 494px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-86e50a5\" data-id=\"86e50a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa64247 elementor-widget elementor-widget-heading\" data-id=\"fa64247\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SACCHETTI DI PLASTICA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4ccab3 elementor-widget elementor-widget-text-editor\" data-id=\"e4ccab3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I sacchetti di plastica rimangono nell\u2019ambiente per molto tempo, possono impiegare fino a 1000 anni per decomporsi e sono responsabili della morte di molti animali marini. Allo zoo non vengono distribuiti, sono stati sostituiti dai sacchetti in carta e Mater-Bi\u00ae, anche se consigliamo vivamente ai nostri visitatori di utilizzare le proprie borse e zaini.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dcec568 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dcec568\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a6b7dc0\" data-id=\"a6b7dc0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e80e872 elementor-widget elementor-widget-image\" data-id=\"e80e872\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"359\" height=\"295\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/materbi.png\" class=\"attachment-large size-large wp-image-7504\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/materbi.png 359w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/materbi-300x247.png 300w\" sizes=\"(max-width: 359px) 100vw, 359px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9df329a\" data-id=\"9df329a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15abc2c elementor-widget elementor-widget-heading\" data-id=\"15abc2c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MATERBI e PLA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a0347a elementor-widget elementor-widget-text-editor\" data-id=\"5a0347a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il Mater-Bi\u00ae e il PLA sono delle bioplastiche biodegradabili e compostabili che consentono di ottimizzare la gestione dei rifiuti organici, riducendo l&#8217;impatto ambientale. Questi materiali sono stati sceltoi per le stoviglie monouso del nostro Ristorante Self-Service.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e07bd5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e07bd5d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-46dfbe1\" data-id=\"46dfbe1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3985293 elementor-widget elementor-widget-image\" data-id=\"3985293\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"365\" height=\"404\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/rubinettob.png\" class=\"attachment-large size-large wp-image-7509\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/rubinettob.png 365w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/rubinettob-271x300.png 271w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-537cac5\" data-id=\"537cac5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db5cf36 elementor-widget elementor-widget-heading\" data-id=\"db5cf36\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RISPARMIO IDRICO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55a285b elementor-widget elementor-widget-text-editor\" data-id=\"55a285b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tL\u2019acqua \u00e8 una risorsa preziosa, che non possiamo sprecare. Tutti i lavandini dei servizi igienici sono dotati di temporizzatori e gli sciacquoni sono dotati del doppio pulsante di scarico dell\u2019acqua.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1fda09c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fda09c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b252540\" data-id=\"b252540\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c623bcd elementor-widget elementor-widget-image\" data-id=\"c623bcd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"287\" height=\"462\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/lampadina-greenb.png\" class=\"attachment-large size-large wp-image-7502\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/lampadina-greenb.png 287w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/lampadina-greenb-186x300.png 186w\" sizes=\"(max-width: 287px) 100vw, 287px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bb39319\" data-id=\"bb39319\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8055fbf elementor-widget elementor-widget-heading\" data-id=\"8055fbf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ILLUMINAZIONE A LED<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-981f3f4 elementor-widget elementor-widget-text-editor\" data-id=\"981f3f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I LED consumano meno energia, diffondono una luce di migliore qualit\u00e0, hanno un minore impatto ambientale e possono durare fino a 20 anni. Tutte le luci dei servizi igienici sono dotate di lampade al LED e di temporizzatori.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e53032f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e53032f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ffb8ee3\" data-id=\"ffb8ee3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56d40e9 elementor-widget elementor-widget-image\" data-id=\"56d40e9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"787\" height=\"306\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/pesce.png\" class=\"attachment-large size-large wp-image-7507\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/pesce.png 787w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/pesce-300x117.png 300w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/pesce-768x299.png 768w\" sizes=\"(max-width: 787px) 100vw, 787px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-365b273\" data-id=\"365b273\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70684a2 elementor-widget elementor-widget-heading\" data-id=\"70684a2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PESCE CERTIFICATO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6f8412 elementor-widget elementor-widget-text-editor\" data-id=\"d6f8412\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pi\u00f9 del 70% degli stock ittici valutati risultano essere sovrasfruttati o al limite dello sfruttamento. Per questo, gli animali piscivori dello zoo vengono alimentati con pesce certificato, nel rispetto del mare e dei pescatori.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9f0140c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f0140c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c2ae90a\" data-id=\"c2ae90a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cf0578 elementor-widget elementor-widget-image\" data-id=\"9cf0578\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"634\" height=\"623\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2025\/06\/cellulare.jpg\" class=\"attachment-large size-large wp-image-10254\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2025\/06\/cellulare.jpg 634w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2025\/06\/cellulare-300x295.jpg 300w\" sizes=\"(max-width: 634px) 100vw, 634px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db1d210\" data-id=\"db1d210\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef6d435 elementor-widget elementor-widget-heading\" data-id=\"ef6d435\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RICICLO CELLULARI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf56d91 elementor-widget elementor-widget-text-editor\" data-id=\"bf56d91\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lo Zoo, con un punto di raccolta, partecipa alla Campagna per il riciclo dei cellulari del <strong><a href=\"https:\/\/www.janegoodall.it\/index.php\/azione\/cellulari\/\">Jane Goodall Institute Italia<\/a> <\/strong>contribuendo alla lotta al degrado ambientale e alla povert\u00e0. Questo gesto consente di ridurre l\u2019accumulo di rifiuti tossici, di recuperare materiali come il coltan, di contrastare lo sfruttamento sul lavoro e di sostenere le spese per l\u2019istruzione dei bambini di Sanganingwa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0b420c4\" data-id=\"0b420c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-90e67ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90e67ba\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4220c7b\" data-id=\"4220c7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd60503 elementor-widget elementor-widget-image\" data-id=\"cd60503\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"350\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/terra-e-foglia.png\" class=\"attachment-large size-large wp-image-7512\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/terra-e-foglia.png 417w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/terra-e-foglia-300x252.png 300w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-15d5653\" data-id=\"15d5653\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acbd10e elementor-widget elementor-widget-heading\" data-id=\"acbd10e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ZOOVENIR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d12e74 elementor-widget elementor-widget-text-editor\" data-id=\"1d12e74\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nel negozio di souvenir dello zoo puoi trovare articoli rispettosi della natura e delle condizioni di lavoro dell\u2019uomo.<\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a877683 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a877683\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1579494\" data-id=\"1579494\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cfc314 elementor-widget elementor-widget-image\" data-id=\"1cfc314\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"396\" height=\"360\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/alberi.png\" class=\"attachment-large size-large wp-image-7491\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/alberi.png 396w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/alberi-300x273.png 300w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bdcfd96\" data-id=\"bdcfd96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cfa0fd elementor-widget elementor-widget-heading\" data-id=\"4cfa0fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PROGETTO TREEDOM<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-384e739 elementor-widget elementor-widget-text-editor\" data-id=\"384e739\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lo Zoo, attraverso il <a href=\"https:\/\/www.parcozoopuntaverde.it\/progetto-treedom\/\">Progetto Treedom,<\/a> ha iniziato a piantare i primi 300 alberi per compensare le proprie emissioni di CO2.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e9365d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e9365d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bb33143\" data-id=\"bb33143\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bde3f73 elementor-widget elementor-widget-image\" data-id=\"bde3f73\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"435\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/foglio-carta.png\" class=\"attachment-large size-large wp-image-7500\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/foglio-carta.png 445w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/foglio-carta-300x293.png 300w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-535ec8a\" data-id=\"535ec8a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52bf597 elementor-widget elementor-widget-heading\" data-id=\"52bf597\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MENO CARTA PIU\u2019 FORESTE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45684e8 elementor-widget elementor-widget-text-editor\" data-id=\"45684e8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il consumo di carta certificata\u00a0<a href=\"https:\/\/it.fsc.org\/it-it\">FSC<\/a>\/<a href=\"https:\/\/www.pefc.it\/\">PEFC<\/a>\u00a0\u00e8 una scelta responsabile che tutela le foreste del mondo. La carta igienica scelta per i servizi igienici dello zoo \u00e8 certificata FSC. Inoltre per non sprecare ulteriore carta, i distributori di salviette sono stati sostituiti con gli asciugamani elettrici a basso consumo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8916993 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8916993\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fece926\" data-id=\"fece926\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-006966e elementor-widget elementor-widget-image\" data-id=\"006966e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"444\" height=\"434\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bottiglia-no-frecce.png\" class=\"attachment-large size-large wp-image-7496\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bottiglia-no-frecce.png 444w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bottiglia-no-frecce-300x293.png 300w\" sizes=\"(max-width: 444px) 100vw, 444px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-937724d\" data-id=\"937724d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-417c71a elementor-widget elementor-widget-heading\" data-id=\"417c71a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CASETTA DELL'ACQUA\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3554fdc elementor-widget elementor-widget-text-editor\" data-id=\"3554fdc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Potete utilizzare le casette dell\u2019acqua, installate vicino ai due bar presenti all&#8217;interno del Parco, per riempire la vostra bottiglia o borraccia. In questo modo insieme, possiamo evitate di appesantire il nostro pianeta con milioni di bottiglie di plastica che ogni giorno finiscono nei rifiuti e poi nel mare.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3035ce8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3035ce8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fd5f0ff\" data-id=\"fd5f0ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb8b7c6 elementor-widget elementor-widget-image\" data-id=\"fb8b7c6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"444\" height=\"434\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bottiglia.png\" class=\"attachment-large size-large wp-image-7497\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bottiglia.png 444w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bottiglia-300x293.png 300w\" sizes=\"(max-width: 444px) 100vw, 444px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-42e2088\" data-id=\"42e2088\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce16dae elementor-widget elementor-widget-heading\" data-id=\"ce16dae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">COMPATTATORE DI BOTTIGLIE DI PLASTICA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9194e4 elementor-widget elementor-widget-text-editor\" data-id=\"a9194e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Al fine di incentivare una raccolta differenziata di qualit\u00e0, mantenendo pulito l&#8217;ambiente e trasformando i rifiuti in risorse, nel bar centrale del Parco \u00e8 presente un compattatore di bottiglie di plastica.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eac9d64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eac9d64\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3faff66\" data-id=\"3faff66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c75451 elementor-widget elementor-widget-image\" data-id=\"5c75451\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"519\" height=\"497\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/riciclo-creativo.png\" class=\"attachment-large size-large wp-image-7508\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/riciclo-creativo.png 519w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/riciclo-creativo-300x287.png 300w\" sizes=\"(max-width: 519px) 100vw, 519px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c7dd41\" data-id=\"6c7dd41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-331d2e0 elementor-widget elementor-widget-heading\" data-id=\"331d2e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RIUSO CREATIVO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-138f689 elementor-widget elementor-widget-text-editor\" data-id=\"138f689\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Allo zoo gli imballaggi in cartone e plastica vengono riutilizzati per realizzare alcuni arricchimenti ambientali. Le attivit\u00e0 di arricchimento ambientale comprendono una moltitudine di dispositivi, tecniche e pratiche innovative, creative e ingegnose, con lo scopo di fornire interazioni sociali adeguate, mantenere occupati gli animali in cattivit\u00e0, permettere un range pi\u00f9 ampio e una maggiore diversit\u00e0 di opportunit\u00e0 comportamentali e creare ambienti pi\u00f9 stimolanti.&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7427a42 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7427a42\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b58d52d\" data-id=\"b58d52d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80ef2a8 elementor-widget elementor-widget-image\" data-id=\"80ef2a8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"392\" height=\"428\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bus1.png\" class=\"attachment-large size-large wp-image-7498\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bus1.png 392w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bus1-275x300.png 275w\" sizes=\"(max-width: 392px) 100vw, 392px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f96f9d9\" data-id=\"f96f9d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-282082a elementor-widget elementor-widget-heading\" data-id=\"282082a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MOBILITA\u2019 SOSTENIBILE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e396346 elementor-widget elementor-widget-text-editor\" data-id=\"e396346\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Le emissioni prodotte da un autobus sono ammortizzate dal fatto di trasportare molte pi\u00f9 persone di una singola auto<\/strong><strong>.\u00a0<\/strong>Lo zoo ha stipulato una convenzione con TPL FVG per incentivare la mobilit\u00e0 sostenibile. Arrivando allo zoo in autobus, il titolo di viaggio, se convalidato entro un\u2019ora, d\u00e0 diritto ad uno sconto di \u20ac 2,00 sul biglietto di ingresso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9386956 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9386956\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-84b8260\" data-id=\"84b8260\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0971103 elementor-widget elementor-widget-image\" data-id=\"0971103\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"686\" height=\"439\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bicicletta.png\" class=\"attachment-large size-large wp-image-7493\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bicicletta.png 686w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/bicicletta-300x192.png 300w\" sizes=\"(max-width: 686px) 100vw, 686px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1903552\" data-id=\"1903552\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10960a3 elementor-widget elementor-widget-text-editor\" data-id=\"10960a3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Raggiungi il Parco con la bici<\/strong>. La bicicletta ti permette inoltre di goderti il panorama lungo il tragitto e se vieni da Bibione utilizza il servizio di <a href=\"https:\/\/lignanosabbiadoro.it\/it\/esperienze\/x-river-traghetto-ciclopedonale-sul-fiume-tagliamento\/\"><strong>traghetto X-River<\/strong> <\/a>per attraversare il fiume Tagliamento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67df45b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67df45b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c6db9d\" data-id=\"0c6db9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63cd483 elementor-widget elementor-widget-text-editor\" data-id=\"63cd483\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"fascia-descrizione-animale-descrizione-tit\"><span class=\"arancione\"><strong>\u201cOggi non \u00e8 che un giorno qualunque di tutti i giorni che verranno, ma quello che accadr\u00e0 in tutti gli altri giorni che verranno pu\u00f2 dipendere da quello che farai tu oggi.\u201d E. Hemingway<\/strong><\/span><\/p><p class=\"fascia-descrizione-animale-descrizione-tit\"><span class=\"arancione\">E TU?<\/span><\/p><div class=\"clear\"><br \/><strong>Il primo consiglio che ti vogliamo dare \u00e8 quello di informati con intelligenza: ci sono centinaia di siti, riviste e programmi tv che parlano di ambiente e sviluppo sostenibile.<\/strong><br \/>\u00a0<\/div><p>Ecco alcuni pratici consigli:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-402438d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"402438d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b48883\" data-id=\"1b48883\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f249ff5 elementor-widget elementor-widget-image\" data-id=\"f249ff5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"725\" height=\"649\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/casetta.png\" class=\"attachment-large size-large wp-image-7499\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/casetta.png 725w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/casetta-300x269.png 300w\" sizes=\"(max-width: 725px) 100vw, 725px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1284021\" data-id=\"1284021\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0360499 elementor-widget elementor-widget-heading\" data-id=\"0360499\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A CASA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36e0964 elementor-widget elementor-widget-text-editor\" data-id=\"36e0964\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Usa le<strong>\u00a0lampadine a risparmio energetico<\/strong>: consumano 5 volte di meno e durano 10 volte di pi\u00f9.<\/li><li><strong>SpegnI il forno o i fornelli qualche minuto prima del termine della cottura<\/strong>, il calore residuo completer\u00e0 la cottura senza ulteriori sprechi.<\/li><li>La sera e prima di andare in vacanza \u00e8 opportuno<strong>\u00a0staccare dalle prese tutti gli apparecchi<\/strong><strong>:<\/strong>\u00a0consumano energia anche in stand-by.<\/li><li>Usa\u00a0<strong>pile ricaricabili<\/strong>: si possono ricaricare fino a 500 volte.<\/li><li>Fai la\u00a0<strong>raccolta differenziata<\/strong>.<\/li><li>Quando usi la lavatrice fai lavaggi a\u00a0<strong>pieno carico<\/strong>.<\/li><li><strong>Aggiusta\u00a0<\/strong>piccoli difetti o scuciture, prima di buttare per pigrizia: un gesto piccolo che pu\u00f2 ridurre una grande mole di rifiuti!<\/li><li><strong>Scegli prodotti a km zero e di stagione:\u00a0<\/strong>mangiare locale \u00e8 una filosofia di consumo sostenibile.<\/li><li><strong>Acqua?<\/strong>\u00a0<strong>Meglio di rubinetto.\u00a0<\/strong>\u00c8 sana perch\u00e9 sottoposta a continui controlli. Risparmi anche pi\u00f9 di 200 euro l\u2019anno perch\u00e9 costa oltre 1000 volte in meno di quella in bottiglia. Non crea rifiuti perch\u00e9 priva di contenitori. Diminuisce l\u2019inquinamento e il traffico dovuto al trasporto su strada delle bottiglie.<\/li><li><strong>Sostituisci i vecchi elettrodomestici<\/strong>\u00a0con modelli ad alta efficienza energetica, (classe A+ o superiore)<\/li><li><strong>Una doccia \u00e8 bella se dura poco<\/strong>: in 3 minuti consumi 40 litri d&#8217;acqua, in 10 minuti pi\u00f9 di 130 litri!<\/li><li>Scegli dentifrici\u00a0 e cosmetici che\u00a0<strong>non contengano microplastiche<\/strong>\u00a0(microgranuli) e ricordati che se lasci scorrere l\u2019acqua mentre ti lavi i denti, getti fino a 30 litri d&#8217;acqua. Aprila solo quando li risciacqui.<\/li><li>Ricorda che la<strong>\u00a0temperatura interna ideale in inverno \u00e8 di 18-20 gradi<\/strong>:\u00a0pi\u00f9 salute per te e per l\u2019ambiente.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-96914d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96914d3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f3114eb\" data-id=\"f3114eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a77e4d8 elementor-widget elementor-widget-image\" data-id=\"a77e4d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"1024\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/pc-694x1024.png\" class=\"attachment-large size-large wp-image-7506\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/pc-694x1024.png 694w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/pc-203x300.png 203w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/pc-768x1134.png 768w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/pc.png 810w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-622c5a6\" data-id=\"622c5a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-093ca79 elementor-widget elementor-widget-heading\" data-id=\"093ca79\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IN UFFICIO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2572e29 elementor-widget elementor-widget-text-editor\" data-id=\"2572e29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Utilizza la\u00a0<strong>tecnologia digitale<\/strong>\u00a0per inviare e ricevere documenti e per informarti: salvi alberi e non inquini con i trasporti.<\/li><li><strong>Recupera i fogli stampati<\/strong>\u00a0da buttare usandoli come \u00abbrutta copia\u00bb.<\/li><li><strong>Porta da casa una tazza o un bicchiere in vetro:<\/strong>\u00a0chi consuma 2 tazze di t\u00e8 al giorno, evita di buttare circa 400 bicchieri di plastica all\u2019anno.<\/li><li><strong>Spegni<\/strong>\u00a0l\u2019interruttore del monitor.<\/li><li>Utilizza\u00a0<strong>carta certificata<\/strong>\u00a0<a href=\"https:\/\/it.fsc.org\/it-it\">FSC<\/a>\/<a href=\"https:\/\/www.pefc.it\/\">PEFC<\/a>.\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b603f93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b603f93\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-112116d\" data-id=\"112116d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74b2eba elementor-widget elementor-widget-image\" data-id=\"74b2eba\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"764\" height=\"798\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/tazza.png\" class=\"attachment-large size-large wp-image-7511\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/tazza.png 764w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/tazza-287x300.png 287w\" sizes=\"(max-width: 764px) 100vw, 764px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-993a01f\" data-id=\"993a01f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e37e2a1 elementor-widget elementor-widget-heading\" data-id=\"e37e2a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AL BAR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-124594d elementor-widget elementor-widget-text-editor\" data-id=\"124594d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Rinuncia alla cannuccia<\/strong>\u00a0se non strettamente necessaria.<\/li><li>Prendi il\u00a0<strong>minor numero di tovaglioli<\/strong>\u00a0possibile, solo quelli che realmente ti servono.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-175d555 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"175d555\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2e190dc\" data-id=\"2e190dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a810a52 elementor-widget elementor-widget-image\" data-id=\"a810a52\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"511\" height=\"516\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/ombellone.png\" class=\"attachment-large size-large wp-image-7505\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/ombellone.png 511w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/ombellone-297x300.png 297w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/ombellone-150x150.png 150w\" sizes=\"(max-width: 511px) 100vw, 511px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f29ed3\" data-id=\"1f29ed3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-245eab2 elementor-widget elementor-widget-heading\" data-id=\"245eab2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IN VACANZA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b489591 elementor-widget elementor-widget-text-editor\" data-id=\"b489591\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Evita di\u00a0<strong>stampare le carte d\u2019imbarco<\/strong>: la versione digitale \u00e8 molto comoda ed ecologica.<\/li><li>Quando viaggi fai attenzione a ci\u00f2 che compri. Diffidare dall\u2019acquisto di\u00a0<strong>articoli di dubbia provenienza<\/strong>\u00a0\u00e8 una valida arma per la riduzione del commercio illegale di animali e piante protetti.<\/li><li>Se scegli di viaggiare attraverso i circuiti del\u00a0<strong><em>turismo responsabile<\/em><\/strong>\u00a0avrai la possibilit\u00e0 di dare il tuo contributo diretto ad una forma di economia virtuosa, equa e sostenibile.<\/li><li>Prediligi\u00a0<strong>mete meno conosciute<\/strong>\u00a0e pi\u00f9 particolari. Evitare di visitare mete famose, solo perch\u00e9 celebri, causa danni, a volte irreparabili, agli ecosistemi, alla flora e alla fauna locale.<\/li><li>Non portarti a casa\u00a0<strong>sabbia<\/strong>,\u00a0<strong>sassi<\/strong>\u00a0dalle spiagge,\u00a0<strong>stelle marine<\/strong>\u00a0o altri esseri viventi. Sottrarre sabbia significa contribuire alla naturale erosione e intaccare i delicati equilibri marini gi\u00e0 minacciati.\u00a0<strong>Osserva gli animali nel loro ambiente<\/strong><\/li><li>Se pratichi lo\u00a0<strong>snorkeling<\/strong>\u00a0o le immersioni subacquee, ricordati di non toccare coralli, pesci, meduse e altri organismi.<\/li><li><strong>Evita di comprare bottiglie<\/strong>\u00a0di plastica e in spiaggia ancora di pi\u00f9. Porta con te delle comode borracce.<\/li><li>Fai la\u00a0<strong>raccolta differenziata<\/strong>.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6bc8186 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bc8186\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d81b0f2\" data-id=\"d81b0f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47db73e elementor-widget elementor-widget-image\" data-id=\"47db73e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"549\" height=\"559\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/forchetta.png\" class=\"attachment-large size-large wp-image-7501\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/forchetta.png 549w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/forchetta-295x300.png 295w\" sizes=\"(max-width: 549px) 100vw, 549px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78ad85c\" data-id=\"78ad85c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1470325 elementor-widget elementor-widget-heading\" data-id=\"1470325\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AL RISTORANTE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-472ed65 elementor-widget elementor-widget-text-editor\" data-id=\"472ed65\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Scegli piatti cucinati con prodotti locali, stagionali, etici e sostenibili.<\/li><li>Chiedi sempre: \u201c<strong>Servite pesce sostenibile<\/strong>?\u201d.<\/li><li>Se non riesci a mangiare tutte le pietanze\u00a0<strong>chiedi un contenitore\u00a0<\/strong>per poterle portare a casa.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e71b8e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e71b8e3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-50334b4\" data-id=\"50334b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12bd414 elementor-widget elementor-widget-image\" data-id=\"12bd414\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"549\" height=\"531\" src=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/supermarket.png\" class=\"attachment-large size-large wp-image-7510\" alt=\"\" srcset=\"https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/supermarket.png 549w, https:\/\/www.parcozoopuntaverde.it\/wp-content\/uploads\/2022\/12\/supermarket-300x290.png 300w\" sizes=\"(max-width: 549px) 100vw, 549px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-14c65ca\" data-id=\"14c65ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ff00ad elementor-widget elementor-widget-heading\" data-id=\"6ff00ad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AL SUPERMERCATO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3193b69 elementor-widget elementor-widget-text-editor\" data-id=\"3193b69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Lo sapevi che\u2026<\/strong><br \/>\u2026nel mondo il 45% di frutta e verdura viene sprecato perch\u00e9\u00a0<strong>compriamo troppo<\/strong>\u00a0o non conserviamo correttamente i cibi?<\/p><p>\u2026<strong>in Italia ogni persona butta circa 80 chili di cibo all&#8217;anno;<\/strong><\/p><p>\u2026<strong>pi\u00f9 del 30% dei rifiuti urbani \u00e8 costituito da imballaggi e contenitori.<\/strong> E spesso, questo, dipende dagli errori che commettiamo al supermercato.<\/p><ul><li>Fai la\u00a0<strong>lista della spesa<\/strong>\u00a0pianificando i pasti della settimana<\/li><li><strong>Curiosit\u00e0<\/strong>: comprare quando si \u00e8 affamati induce ad acquisti compulsivi ed eccessivi. Tienilo\u00a0presente.<\/li><li>Ricorda di portare sempre con te le\u00a0<strong>borse riutilizzabili<\/strong>.<\/li><li>\u200b<strong>Consuma prodotti locali<\/strong>: il trasporto dei prodotti comporta alti consumi di petrolio.<\/li><li>Acquista prodotti <strong>sfusi<\/strong> o con <strong>poco imballaggio<\/strong>.<\/li><li>Leggi le\u00a0<strong>etichette<\/strong>.<\/li><li>Scegli le certificazioni\u00a0<strong><a href=\"https:\/\/it.fsc.org\/it-it\">FSC<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.pefc.it\/\">PEFC<\/a><\/strong>\u00a0per gli acquisti di carta assorbente, fazzoletti, carta igienica, quaderni, matite\u2026<\/li><li>Compra pesce sostenibile (ricerca le certificazioni\u00a0<strong><a href=\"https:\/\/www.msc.org\/it\">MSC<\/a><\/strong>,\u00a0<strong><a href=\"https:\/\/www.asc-aqua.org\/\">ASC<\/a><\/strong>,\u00a0<strong><a href=\"https:\/\/friendofthesea.org\/it\/\">Friend of the Sea<\/a><\/strong>), scegli le\u00a0<a href=\"http:\/\/slowfoodgorgonzola.it\/wp-content\/uploads\/2011\/06\/Pesce.pdf\">specie neglette<\/a>, leggi con attenzione l\u2019etichetta, mangia solo pesce adulto, sostieni la piccola pesca artigiana.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LO ZOOSOSTENIBILE Crediamo in un futuro migliore in cui l\u2019uomo possa vivere in armonia con la Natura. Poniamo attenzione al peso che le nostre azioni possono avere sull\u2019ambiente e cerchiamo continuamente di migliorarci per diventare sempre pi\u00f9 sostenibili. RACCOLTA DIFFERENZIATA Riciclare e ridurre i rifiuti \u00e8 un gesto semplice che ha impatti molto positivi sull\u2019ambiente. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_mo_disable_npp":"","footnotes":""},"class_list":["post-7478","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.parcozoopuntaverde.it\/en\/wp-json\/wp\/v2\/pages\/7478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parcozoopuntaverde.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.parcozoopuntaverde.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.parcozoopuntaverde.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parcozoopuntaverde.it\/en\/wp-json\/wp\/v2\/comments?post=7478"}],"version-history":[{"count":16,"href":"https:\/\/www.parcozoopuntaverde.it\/en\/wp-json\/wp\/v2\/pages\/7478\/revisions"}],"predecessor-version":[{"id":10546,"href":"https:\/\/www.parcozoopuntaverde.it\/en\/wp-json\/wp\/v2\/pages\/7478\/revisions\/10546"}],"wp:attachment":[{"href":"https:\/\/www.parcozoopuntaverde.it\/en\/wp-json\/wp\/v2\/media?parent=7478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}